{"id":2,"name":"Robert Faber","url":"","description":"Robert \u00e9 um viajante entusiasta e adepto das novas tecnologias. Sabe cozinhar bem, mas nunca tem tempo suficiente para o fazer e acaba por se queixar da maioria das refei\u00e7\u00f5es. \u00c9 um frequentador ass\u00edduo do gin\u00e1sio.","link":"https:\/\/vasco-translator.pt\/artigos\/autor\/r-faber\/","slug":"r-faber","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vasco Blog | O autor por detr\u00e1s dos nossos artigos<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a a mente por detr\u00e1s do Blogue Vasco. Saiba mais sobre a sua experi\u00eancia em l\u00ednguas, viagens e o que o leva a partilhar consigo dicas e conhecimentos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Vasco Blog | O autor por detr\u00e1s dos nossos artigos\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a a mente por detr\u00e1s do Blogue Vasco. Saiba mais sobre a sua experi\u00eancia em l\u00ednguas, viagens e o que o leva a partilhar consigo dicas e conhecimentos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/\" \/>\n<meta property=\"og:site_name\" content=\"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/a96f4e72658f519a244724e6a6ca91a7?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/author\\\/r-faber\\\/\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/author\\\/r-faber\\\/\",\"name\":\"Vasco Blog | O autor por detr\u00e1s dos nossos artigos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#website\"},\"description\":\"Conhe\u00e7a a mente por detr\u00e1s do Blogue Vasco. Saiba mais sobre a sua experi\u00eancia em l\u00ednguas, viagens e o que o leva a partilhar consigo dicas e conhecimentos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/author\\\/r-faber\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/author\\\/r-faber\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/author\\\/r-faber\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Robert Faber\",\"item\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-json\\\/wp\\\/v2\\\/users\\\/2\"}}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#website\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/\",\"name\":\"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens\",\"description\":\"Descubra o fascinante mundo das l\u00ednguas e das viagens com o Vasco. Mergulhe em artigos, dicas e ideias que o ajudam a tirar o m\u00e1ximo partido das suas viagens.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#\\\/schema\\\/person\\\/277c68c00de8d199cdfebdfa875a8327\",\"name\":\"Robert Faber\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=96&d=mm&r=g\",\"caption\":\"Robert Faber\"},\"description\":\"Robert \u00e9 um viajante entusiasta e adepto das novas tecnologias. Sabe cozinhar bem, mas nunca tem tempo suficiente para o fazer e acaba por se queixar da maioria das refei\u00e7\u00f5es. \u00c9 um frequentador ass\u00edduo do gin\u00e1sio.\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/author\\\/r-faber\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vasco Blog | O autor por detr\u00e1s dos nossos artigos","description":"Conhe\u00e7a a mente por detr\u00e1s do Blogue Vasco. Saiba mais sobre a sua experi\u00eancia em l\u00ednguas, viagens e o que o leva a partilhar consigo dicas e conhecimentos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/","og_locale":"pt_PT","og_type":"profile","og_title":"Vasco Blog | O autor por detr\u00e1s dos nossos artigos","og_description":"Conhe\u00e7a a mente por detr\u00e1s do Blogue Vasco. Saiba mais sobre a sua experi\u00eancia em l\u00ednguas, viagens e o que o leva a partilhar consigo dicas e conhecimentos.","og_url":"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/","og_site_name":"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/a96f4e72658f519a244724e6a6ca91a7?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/","url":"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/","name":"Vasco Blog | O autor por detr\u00e1s dos nossos artigos","isPartOf":{"@id":"https:\/\/vasco-translator.pt\/artigos\/#website"},"description":"Conhe\u00e7a a mente por detr\u00e1s do Blogue Vasco. Saiba mais sobre a sua experi\u00eancia em l\u00ednguas, viagens e o que o leva a partilhar consigo dicas e conhecimentos.","breadcrumb":{"@id":"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vasco-translator.pt\/artigos\/"},{"@type":"ListItem","position":2,"name":"Robert Faber","item":{"@id":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/users\/2"}}]},{"@type":"WebSite","@id":"https:\/\/vasco-translator.pt\/artigos\/#website","url":"https:\/\/vasco-translator.pt\/artigos\/","name":"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","description":"Descubra o fascinante mundo das l\u00ednguas e das viagens com o Vasco. Mergulhe em artigos, dicas e ideias que o ajudam a tirar o m\u00e1ximo partido das suas viagens.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vasco-translator.pt\/artigos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/vasco-translator.pt\/artigos\/#\/schema\/person\/277c68c00de8d199cdfebdfa875a8327","name":"Robert Faber","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/faf3843011254f7ef2dd7d5c9be102ecdbb8f4e24d38417f6d13027aff523c07?s=96&d=mm&r=g","caption":"Robert Faber"},"description":"Robert \u00e9 um viajante entusiasta e adepto das novas tecnologias. Sabe cozinhar bem, mas nunca tem tempo suficiente para o fazer e acaba por se queixar da maioria das refei\u00e7\u00f5es. \u00c9 um frequentador ass\u00edduo do gin\u00e1sio.","mainEntityOfPage":{"@id":"https:\/\/vasco-translator.pt\/artigos\/author\/r-faber\/"}}]}},"_links":{"self":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/users\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/users"}]}}