{"id":1448,"date":"2024-07-22T13:15:18","date_gmt":"2024-07-22T13:15:18","guid":{"rendered":"https:\/\/vasco-translator.pt\/artigos\/?p=1448"},"modified":"2025-08-12T10:21:29","modified_gmt":"2025-08-12T10:21:29","slug":"a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator","status":"publish","type":"post","link":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/","title":{"rendered":"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator"},"content":{"rendered":"<p>Do\u00e1mos um <a href='https:\/\/vasco-translator.pt\/tradutor\/vasco-translator-v4'>Vasco Translator V4<\/a> ao Sr. Kamio Nobumitsu &#8211; Primeiro Secret\u00e1rio e Chefe da Sec\u00e7\u00e3o Econ\u00f3mica da Embaixada do Jap\u00e3o na Pol\u00f3nia. O aparelho ir\u00e1 apoiar os funcion\u00e1rios que viajam para o estrangeiro em miss\u00f5es diplom\u00e1ticas.<\/p>\n<p>O Sr. Kamio Nobumitsu desempenhou anteriormente fun\u00e7\u00f5es nos Estados Unidos, bem como no Iraque e na B\u00f3snia e Herzegovina, onde participou na reconstru\u00e7\u00e3o p\u00f3s-guerra. Trabalha na Pol\u00f3nia h\u00e1 oito anos e, no ano passado, foi nomeado para o seu cargo atual na embaixada. Reconhecemos o enorme potencial do mercado japon\u00eas, no qual inici\u00e1mos a nossa atividade com os nossos tradutores h\u00e1 v\u00e1rios anos.<\/p>\n<p>Estamos constantemente a esfor\u00e7ar-nos por aumentar a nossa presen\u00e7a no Jap\u00e3o, por isso estamos satisfeitos por um representante da embaixada do pa\u00eds ter depositado grande confian\u00e7a em n\u00f3s. Estamos satisfeitos por ele ter apreciado o valor do Vasco Translator, abrindo-nos novas oportunidades de coopera\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do\u00e1mos um Vasco Translator V4 ao Sr. Kamio Nobumitsu &#8211; Primeiro Secret\u00e1rio e Chefe da Sec\u00e7\u00e3o Econ\u00f3mica da Embaixada do Jap\u00e3o na Pol\u00f3nia. O aparelho ir\u00e1 apoiar os funcion\u00e1rios que viajam para o estrangeiro em miss\u00f5es diplom\u00e1ticas. O Sr. Kamio Nobumitsu desempenhou anteriormente fun\u00e7\u00f5es nos Estados Unidos, bem como no Iraque e na B\u00f3snia e [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[37],"tags":[40],"class_list":["post-1448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-a-noskowska"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator - Vasco Blog | Explorar factos sobre l\u00ednguas e viagens<\/title>\n<meta name=\"description\" content=\"Do\u00e1mos um Vasco Translator V4 ao Primeiro Secret\u00e1rio da Embaixada do Jap\u00e3o na Pol\u00f3nia para facilitar as miss\u00f5es diplom\u00e1ticas no estrangeiro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator - Vasco Blog | Explorar factos sobre l\u00ednguas e viagens\" \/>\n<meta property=\"og:description\" content=\"Do\u00e1mos um Vasco Translator V4 ao Primeiro Secret\u00e1rio da Embaixada do Jap\u00e3o na Pol\u00f3nia para facilitar as miss\u00f5es diplom\u00e1ticas no estrangeiro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/\" \/>\n<meta property=\"og:site_name\" content=\"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-22T13:15:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T10:21:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/08\/Projekt-bez-nazwy-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1252\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Agnieszka Noskowska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agnieszka Noskowska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/\"},\"author\":{\"name\":\"Agnieszka Noskowska\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#\\\/schema\\\/person\\\/a580053ebb76efc7205f34bd7d74b31d\"},\"headline\":\"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator\",\"datePublished\":\"2024-07-22T13:15:18+00:00\",\"dateModified\":\"2025-08-12T10:21:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/\"},\"wordCount\":181,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Projekt-bez-nazwy-4.png\",\"keywords\":[\"Agnieszka Noskowska\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/#respond\"]}],\"timeRequired\":\"PT1M\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/\",\"name\":\"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator - Vasco Blog | Explorar factos sobre l\u00ednguas e viagens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Projekt-bez-nazwy-4.png\",\"datePublished\":\"2024-07-22T13:15:18+00:00\",\"dateModified\":\"2025-08-12T10:21:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#\\\/schema\\\/person\\\/a580053ebb76efc7205f34bd7d74b31d\"},\"description\":\"Do\u00e1mos um Vasco Translator V4 ao Primeiro Secret\u00e1rio da Embaixada do Jap\u00e3o na Pol\u00f3nia para facilitar as miss\u00f5es diplom\u00e1ticas no estrangeiro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Projekt-bez-nazwy-4.png\",\"contentUrl\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Projekt-bez-nazwy-4.png\",\"width\":1252,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator\",\"item\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/1448\"}}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#website\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/\",\"name\":\"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens\",\"description\":\"Descubra o fascinante mundo das l\u00ednguas e das viagens com o Vasco. Mergulhe em artigos, dicas e ideias que o ajudam a tirar o m\u00e1ximo partido das suas viagens.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#\\\/schema\\\/person\\\/a580053ebb76efc7205f34bd7d74b31d\",\"name\":\"Agnieszka Noskowska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g\",\"caption\":\"Agnieszka Noskowska\"},\"description\":\"Agnieszka Noskowska, desde o in\u00edcio da sua carreira que est\u00e1 ligada ao marketing e h\u00e1 v\u00e1rios anos que se dedica \u00e0s rela\u00e7\u00f5es p\u00fablicas, onde \u00e9 apaixonada por projectos criativos. Encontra o equil\u00edbrio no ciclismo de estrada, nas caminhadas de montanha e na bricolage. Embora adore o seu trabalho, se pudesse voltar a escolher uma carreira, tornar-se-ia carpinteira, de forma a combinar o seu amor pelo artesanato e pela natureza.\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/autor\\\/a-noskowska\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator - Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","description":"Do\u00e1mos um Vasco Translator V4 ao Primeiro Secret\u00e1rio da Embaixada do Jap\u00e3o na Pol\u00f3nia para facilitar as miss\u00f5es diplom\u00e1ticas no estrangeiro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/","og_locale":"pt_PT","og_type":"article","og_title":"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator - Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","og_description":"Do\u00e1mos um Vasco Translator V4 ao Primeiro Secret\u00e1rio da Embaixada do Jap\u00e3o na Pol\u00f3nia para facilitar as miss\u00f5es diplom\u00e1ticas no estrangeiro.","og_url":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/","og_site_name":"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","article_published_time":"2024-07-22T13:15:18+00:00","article_modified_time":"2025-08-12T10:21:29+00:00","og_image":[{"width":1252,"height":701,"url":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/08\/Projekt-bez-nazwy-4.png","type":"image\/png"}],"author":"Agnieszka Noskowska","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Agnieszka Noskowska","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/#article","isPartOf":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/"},"author":{"name":"Agnieszka Noskowska","@id":"https:\/\/vasco-translator.pt\/artigos\/#\/schema\/person\/a580053ebb76efc7205f34bd7d74b31d"},"headline":"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator","datePublished":"2024-07-22T13:15:18+00:00","dateModified":"2025-08-12T10:21:29+00:00","mainEntityOfPage":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/"},"wordCount":181,"commentCount":0,"image":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/#primaryimage"},"thumbnailUrl":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/08\/Projekt-bez-nazwy-4.png","keywords":["Agnieszka Noskowska"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/#respond"]}],"timeRequired":"PT1M"},{"@type":"WebPage","@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/","url":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/","name":"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator - Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","isPartOf":{"@id":"https:\/\/vasco-translator.pt\/artigos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/#primaryimage"},"image":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/#primaryimage"},"thumbnailUrl":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/08\/Projekt-bez-nazwy-4.png","datePublished":"2024-07-22T13:15:18+00:00","dateModified":"2025-08-12T10:21:29+00:00","author":{"@id":"https:\/\/vasco-translator.pt\/artigos\/#\/schema\/person\/a580053ebb76efc7205f34bd7d74b31d"},"description":"Do\u00e1mos um Vasco Translator V4 ao Primeiro Secret\u00e1rio da Embaixada do Jap\u00e3o na Pol\u00f3nia para facilitar as miss\u00f5es diplom\u00e1ticas no estrangeiro.","breadcrumb":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/#primaryimage","url":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/08\/Projekt-bez-nazwy-4.png","contentUrl":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/08\/Projekt-bez-nazwy-4.png","width":1252,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/vasco-translator.pt\/artigos\/news\/a-embaixada-do-japao-na-polonia-vai-utilizar-o-vasco-translator\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vasco-translator.pt\/artigos\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/vasco-translator.pt\/artigos\/category\/news\/"},{"@type":"ListItem","position":3,"name":"A Embaixada do Jap\u00e3o na Pol\u00f3nia vai utilizar o Vasco Translator","item":{"@id":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts\/1448"}}]},{"@type":"WebSite","@id":"https:\/\/vasco-translator.pt\/artigos\/#website","url":"https:\/\/vasco-translator.pt\/artigos\/","name":"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","description":"Descubra o fascinante mundo das l\u00ednguas e das viagens com o Vasco. Mergulhe em artigos, dicas e ideias que o ajudam a tirar o m\u00e1ximo partido das suas viagens.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vasco-translator.pt\/artigos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/vasco-translator.pt\/artigos\/#\/schema\/person\/a580053ebb76efc7205f34bd7d74b31d","name":"Agnieszka Noskowska","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g","caption":"Agnieszka Noskowska"},"description":"Agnieszka Noskowska, desde o in\u00edcio da sua carreira que est\u00e1 ligada ao marketing e h\u00e1 v\u00e1rios anos que se dedica \u00e0s rela\u00e7\u00f5es p\u00fablicas, onde \u00e9 apaixonada por projectos criativos. Encontra o equil\u00edbrio no ciclismo de estrada, nas caminhadas de montanha e na bricolage. Embora adore o seu trabalho, se pudesse voltar a escolher uma carreira, tornar-se-ia carpinteira, de forma a combinar o seu amor pelo artesanato e pela natureza.","url":"https:\/\/vasco-translator.pt\/artigos\/autor\/a-noskowska\/"}]}},"_links":{"self":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts\/1448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/comments?post=1448"}],"version-history":[{"count":1,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts\/1448\/revisions"}],"predecessor-version":[{"id":1449,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts\/1448\/revisions\/1449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/media\/1450"}],"wp:attachment":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/media?parent=1448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/categories?post=1448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/tags?post=1448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}