{"id":1272,"date":"2023-12-01T14:18:48","date_gmt":"2023-12-01T14:18:48","guid":{"rendered":"https:\/\/vasco-translator.pt\/artigos\/?p=1272"},"modified":"2025-01-29T15:15:58","modified_gmt":"2025-01-29T15:15:58","slug":"o-pai-natal-vasco","status":"publish","type":"post","link":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/","title":{"rendered":"O Pai Natal Vasco para idosos e crian\u00e7as de fam\u00edlias refugiadas"},"content":{"rendered":"<p>Na Vasco, come\u00e7amos o m\u00eas de dezembro com o esp\u00edrito festivo no nosso escrit\u00f3rio. Durante esta \u00e9poca encantadora, dedicamos os nossos esfor\u00e7os \u00e0 prepara\u00e7\u00e3o de pacotes de presentes para crian\u00e7as refugiadas e idosos que enfrentam v\u00e1rias dificuldades.<\/p>\n<p>Ano ap\u00f3s ano, comprometemo-nos a apoiar diversas causas de caridade. A nossa equipa \u00e9 constitu\u00edda por pessoas genuinamente calorosas e solid\u00e1rias. Estamos felizes com a oportunidade de causar um impacto positivo e empenhados em espalhar alegria e bondade na comunidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na Vasco, come\u00e7amos o m\u00eas de dezembro com o esp\u00edrito festivo no nosso escrit\u00f3rio. Durante esta \u00e9poca encantadora, dedicamos os nossos esfor\u00e7os \u00e0 prepara\u00e7\u00e3o de pacotes de presentes para crian\u00e7as refugiadas e idosos que enfrentam v\u00e1rias dificuldades. Ano ap\u00f3s ano, comprometemo-nos a apoiar diversas causas de caridade. A nossa equipa \u00e9 constitu\u00edda por pessoas genuinamente [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[37],"tags":[40],"class_list":["post-1272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-a-noskowska"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Pai Natal Vasco para fam\u00edlias refugiadas<\/title>\n<meta name=\"description\" content=\"Iniciamos o m\u00eas de dezembro no escrit\u00f3rio com a prepara\u00e7\u00e3o de cabazes de presentes para crian\u00e7as refugiadas e pessoas idosas que enfrentam v\u00e1rias dificuldades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Pai Natal Vasco para fam\u00edlias refugiadas\" \/>\n<meta property=\"og:description\" content=\"Iniciamos o m\u00eas de dezembro no escrit\u00f3rio com a prepara\u00e7\u00e3o de cabazes de presentes para crian\u00e7as refugiadas e pessoas idosas que enfrentam v\u00e1rias dificuldades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/\" \/>\n<meta property=\"og:site_name\" content=\"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-01T14:18:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T15:15:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/03\/1702462739299.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agnieszka Noskowska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agnieszka Noskowska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/\"},\"author\":{\"name\":\"Agnieszka Noskowska\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#\\\/schema\\\/person\\\/a580053ebb76efc7205f34bd7d74b31d\"},\"headline\":\"O Pai Natal Vasco para idosos e crian\u00e7as de fam\u00edlias refugiadas\",\"datePublished\":\"2023-12-01T14:18:48+00:00\",\"dateModified\":\"2025-01-29T15:15:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/\"},\"wordCount\":99,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/1702462739299.jpg\",\"keywords\":[\"Agnieszka Noskowska\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/#respond\"]}],\"timeRequired\":\"PT1M\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/\",\"name\":\"O Pai Natal Vasco para fam\u00edlias refugiadas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/1702462739299.jpg\",\"datePublished\":\"2023-12-01T14:18:48+00:00\",\"dateModified\":\"2025-01-29T15:15:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#\\\/schema\\\/person\\\/a580053ebb76efc7205f34bd7d74b31d\"},\"description\":\"Iniciamos o m\u00eas de dezembro no escrit\u00f3rio com a prepara\u00e7\u00e3o de cabazes de presentes para crian\u00e7as refugiadas e pessoas idosas que enfrentam v\u00e1rias dificuldades.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/1702462739299.jpg\",\"contentUrl\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/1702462739299.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"O Pai Natal Vasco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/news\\\/o-pai-natal-vasco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/category\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O Pai Natal Vasco para idosos e crian\u00e7as de fam\u00edlias refugiadas\",\"item\":{\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/wp-json\\\/wp\\\/v2\\\/posts\\\/1272\"}}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#website\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/\",\"name\":\"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens\",\"description\":\"Descubra o fascinante mundo das l\u00ednguas e das viagens com o Vasco. Mergulhe em artigos, dicas e ideias que o ajudam a tirar o m\u00e1ximo partido das suas viagens.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/#\\\/schema\\\/person\\\/a580053ebb76efc7205f34bd7d74b31d\",\"name\":\"Agnieszka Noskowska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g\",\"caption\":\"Agnieszka Noskowska\"},\"description\":\"Agnieszka Noskowska, desde o in\u00edcio da sua carreira que est\u00e1 ligada ao marketing e h\u00e1 v\u00e1rios anos que se dedica \u00e0s rela\u00e7\u00f5es p\u00fablicas, onde \u00e9 apaixonada por projectos criativos. Encontra o equil\u00edbrio no ciclismo de estrada, nas caminhadas de montanha e na bricolage. Embora adore o seu trabalho, se pudesse voltar a escolher uma carreira, tornar-se-ia carpinteira, de forma a combinar o seu amor pelo artesanato e pela natureza.\",\"url\":\"https:\\\/\\\/vasco-translator.pt\\\/artigos\\\/autor\\\/a-noskowska\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Pai Natal Vasco para fam\u00edlias refugiadas","description":"Iniciamos o m\u00eas de dezembro no escrit\u00f3rio com a prepara\u00e7\u00e3o de cabazes de presentes para crian\u00e7as refugiadas e pessoas idosas que enfrentam v\u00e1rias dificuldades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/","og_locale":"pt_PT","og_type":"article","og_title":"O Pai Natal Vasco para fam\u00edlias refugiadas","og_description":"Iniciamos o m\u00eas de dezembro no escrit\u00f3rio com a prepara\u00e7\u00e3o de cabazes de presentes para crian\u00e7as refugiadas e pessoas idosas que enfrentam v\u00e1rias dificuldades.","og_url":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/","og_site_name":"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","article_published_time":"2023-12-01T14:18:48+00:00","article_modified_time":"2025-01-29T15:15:58+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/03\/1702462739299.jpg","type":"image\/jpeg"}],"author":"Agnieszka Noskowska","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Agnieszka Noskowska","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/#article","isPartOf":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/"},"author":{"name":"Agnieszka Noskowska","@id":"https:\/\/vasco-translator.pt\/artigos\/#\/schema\/person\/a580053ebb76efc7205f34bd7d74b31d"},"headline":"O Pai Natal Vasco para idosos e crian\u00e7as de fam\u00edlias refugiadas","datePublished":"2023-12-01T14:18:48+00:00","dateModified":"2025-01-29T15:15:58+00:00","mainEntityOfPage":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/"},"wordCount":99,"commentCount":0,"image":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/#primaryimage"},"thumbnailUrl":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/03\/1702462739299.jpg","keywords":["Agnieszka Noskowska"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/#respond"]}],"timeRequired":"PT1M"},{"@type":"WebPage","@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/","url":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/","name":"O Pai Natal Vasco para fam\u00edlias refugiadas","isPartOf":{"@id":"https:\/\/vasco-translator.pt\/artigos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/#primaryimage"},"image":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/#primaryimage"},"thumbnailUrl":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/03\/1702462739299.jpg","datePublished":"2023-12-01T14:18:48+00:00","dateModified":"2025-01-29T15:15:58+00:00","author":{"@id":"https:\/\/vasco-translator.pt\/artigos\/#\/schema\/person\/a580053ebb76efc7205f34bd7d74b31d"},"description":"Iniciamos o m\u00eas de dezembro no escrit\u00f3rio com a prepara\u00e7\u00e3o de cabazes de presentes para crian\u00e7as refugiadas e pessoas idosas que enfrentam v\u00e1rias dificuldades.","breadcrumb":{"@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/#primaryimage","url":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/03\/1702462739299.jpg","contentUrl":"https:\/\/vasco-translator.pt\/artigos\/wp-content\/uploads\/2024\/03\/1702462739299.jpg","width":2048,"height":1365,"caption":"O Pai Natal Vasco"},{"@type":"BreadcrumbList","@id":"https:\/\/vasco-translator.pt\/artigos\/news\/o-pai-natal-vasco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vasco-translator.pt\/artigos\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/vasco-translator.pt\/artigos\/category\/news\/"},{"@type":"ListItem","position":3,"name":"O Pai Natal Vasco para idosos e crian\u00e7as de fam\u00edlias refugiadas","item":{"@id":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts\/1272"}}]},{"@type":"WebSite","@id":"https:\/\/vasco-translator.pt\/artigos\/#website","url":"https:\/\/vasco-translator.pt\/artigos\/","name":"Vasco Blog | Explorar factos sobre l\u00ednguas e viagens","description":"Descubra o fascinante mundo das l\u00ednguas e das viagens com o Vasco. Mergulhe em artigos, dicas e ideias que o ajudam a tirar o m\u00e1ximo partido das suas viagens.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vasco-translator.pt\/artigos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/vasco-translator.pt\/artigos\/#\/schema\/person\/a580053ebb76efc7205f34bd7d74b31d","name":"Agnieszka Noskowska","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb5825258beecfcbb4c1c72b91d92c7d2db4dddaf4edb0cce24405ba02ee62bc?s=96&d=mm&r=g","caption":"Agnieszka Noskowska"},"description":"Agnieszka Noskowska, desde o in\u00edcio da sua carreira que est\u00e1 ligada ao marketing e h\u00e1 v\u00e1rios anos que se dedica \u00e0s rela\u00e7\u00f5es p\u00fablicas, onde \u00e9 apaixonada por projectos criativos. Encontra o equil\u00edbrio no ciclismo de estrada, nas caminhadas de montanha e na bricolage. Embora adore o seu trabalho, se pudesse voltar a escolher uma carreira, tornar-se-ia carpinteira, de forma a combinar o seu amor pelo artesanato e pela natureza.","url":"https:\/\/vasco-translator.pt\/artigos\/autor\/a-noskowska\/"}]}},"_links":{"self":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts\/1272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/comments?post=1272"}],"version-history":[{"count":2,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts\/1272\/revisions"}],"predecessor-version":[{"id":1513,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/posts\/1272\/revisions\/1513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/media?parent=1272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/categories?post=1272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vasco-translator.pt\/artigos\/wp-json\/wp\/v2\/tags?post=1272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}